{"id":182,"date":"2024-03-04T16:43:30","date_gmt":"2024-03-04T16:43:30","guid":{"rendered":"https:\/\/camround.com\/?p=182"},"modified":"2024-03-05T15:26:13","modified_gmt":"2024-03-05T13:26:13","slug":"chatruletka","status":"publish","type":"post","link":"https:\/\/camround.com\/de\/chatruletka\/","title":{"rendered":"Chatruletka"},"content":{"rendered":"<p>Chatruletka ist ein beliebtes <a href=\"https:\/\/camround.com\/de\/randomskip\/\">zuf\u00e4llig<\/a> <a href=\"https:\/\/camround.com\/de\/chatogo\/\">Video-Chat<\/a> Plattform. Seit dem Start der App vor einigen Jahren hat sie sich zur bevorzugten Plattform f\u00fcr Menschen entwickelt, die Kontakte kn\u00fcpfen und <a href=\"https:\/\/camround.com\/de\/tinychat\/\">Chat<\/a> mit zuf\u00e4lligen Fremden auf der ganzen Welt. Die Plattform hat Berichten zufolge \u00fcber 200.000 aktive Nutzer. Wenn Sie sich also langweilen und nach einer Plattform suchen, \u00fcber die Sie ganz einfach mit anderen zuf\u00e4lligen Fremden in Kontakt treten k\u00f6nnen, werden Sie Chatruletka lieben. Bleiben Sie bei uns, wenn wir Ihnen einen detaillierten \u00dcberblick \u00fcber diese Plattform geben.<\/p>\n<h2>Wie man Chatruletka verwendet<\/h2>\n<p>Chatruletka hat eine der \u00fcbersichtlichsten und intuitivsten Websites, die wir je gesehen haben. Dank des brillanten Designs dieser Plattform kann jeder die Plattform nutzen, um zuf\u00e4llige Fremde zu treffen. Und genau wie die meisten zuf\u00e4lligen <a href=\"https:\/\/camround.com\/de\/coomeet\/\">Video-Chat<\/a> Sites m\u00fcssen Sie sich nicht erst f\u00fcr ein Konto registrieren oder ein umfassendes Profil erstellen, bevor Sie mit dem Chatten beginnen k\u00f6nnen. Sie m\u00fcssen lediglich die Plattform \u00fcber Ihren Lieblingsbrowser besuchen und auf die Schaltfl\u00e4che \"Start\" tippen. Die Plattform sollte Sie sofort mit anderen <a href=\"https:\/\/camround.com\/de\/chatpig\/\">beliebige Benutzer<\/a> siehe <a href=\"https:\/\/camround.com\/de\/bazoocam\/\">zu chatten<\/a>. Das Spannendste an der ganzen Sache ist, dass man sich mit Leuten unterhalten kann, die \u00e4hnliche Interessen haben wie man selbst.<\/p>\n<p>Au\u00dferdem k\u00f6nnen Sie entweder per Text oder per Video chatten, je nachdem, wie Sie sich am wohlsten dabei f\u00fchlen.<\/p>\n<h2>Die wichtigsten Merkmale von Chatruletka<\/h2>\n<p>Chatruletka hat viele aufregende Funktionen, die Ihr Chatterlebnis absolut erstaunlich machen. Abgesehen davon, dass es benutzerfreundlich ist, sind hier einige der Top-Funktionen, die Chatrulteka zu einem absoluten Knaller machen.<\/p>\n<h3>Keine Anmeldung erforderlich<\/h3>\n<p>Die Anmeldung bei Chatruletka ist problemlos und das Beste daran ist, dass Sie sich nicht erst ein Konto anlegen m\u00fcssen, bevor Sie anfangen k\u00f6nnen, mit zuf\u00e4lligen Fremden zu chatten. Um ein Gespr\u00e4ch zu beginnen, m\u00fcssen Sie nur die Plattform besuchen und auf die Schaltfl\u00e4che \"Start\" tippen, dann wird die Seite <a href=\"https:\/\/camround.com\/de\/cammatch\/\">Spiel<\/a> Sie sofort zu jemandem, der bereit ist zu chatten.<\/p>\n<h3>100% frei<\/h3>\n<p>Im Gegensatz zu vielen kostenpflichtigen Plattformen, bei denen man f\u00fcr bestimmte Tarife bezahlen muss, bevor man chatten darf, wird Chatruletka kostenlos angeboten. Alles, was Sie brauchen, ist ein Smartphone, ein Laptop, ein Tablet, ein Desktop-Computer und eine gute Internetverbindung, um mit dem Chatten zu beginnen.<\/p>\n<h3>\nMehrere Chatr\u00e4ume<\/h3>\n<p>Wenn Sie den Nervenkitzel und die Aufregung lieben, die mit Chatrooms einhergehen, werden Sie diese Funktion definitiv lieben. Dank dieser Funktion k\u00f6nnen Sie in mehreren Chatr\u00e4umen chatten, die Ihren Interessen entsprechen.<\/p>\n<h3>Text-Chat<\/h3>\n<p>Die <a href=\"https:\/\/camround.com\/de\/chitchat\/\">Text-Chat<\/a> Mit dieser Funktion k\u00f6nnen Benutzer ohne Videofunktion chatten, sodass sie sich gegenseitig sehen k\u00f6nnen. Text-Chat ist eine gute Option f\u00fcr Personen, die ihre Privatsph\u00e4re und Anonymit\u00e4t online oder in Chatrooms sch\u00fctzen m\u00f6chten.<\/p>\n<h3>Video-Chat<\/h3>\n<p>Zus\u00e4tzlich zum Text-Chat, <a href=\"https:\/\/camround.com\/de\/camloo\/\">Video-Chats<\/a> sind immersiver und finden in Echtzeit \u00fcber eine Webcam statt. Fremde k\u00f6nnen sich mit anderen Fremden \u00fcber Sprache und Video verbinden und videochatten. Sie k\u00f6nnen auch einen Einzelchat oder einen Gruppen-Videochat f\u00fchren. Wenn die Nutzer kein Interesse an einem Chat mit einem Fremden haben oder den Chat beenden m\u00f6chten, k\u00f6nnen sie einfach zum n\u00e4chsten Chat \u00fcbergehen. So einfach ist das.<br \/>\nVor- und Nachteile von Chatruletka<\/p>\n<h3>Profis<\/h3>\n<ul>\n<li>Die Nutzer m\u00fcssen sich nicht erst f\u00fcr ein Konto anmelden, bevor sie mit zuf\u00e4lligen Fremden chatten k\u00f6nnen.<\/li>\n<li>Die Plattform wird kostenlos angeboten<\/li>\n<li>Die Plattform unterst\u00fctzt mehrere Sprachen<\/li>\n<li>Chatruletka hat \u00fcber 200.000 aktive Benutzer, es gibt also keinen Mangel an Leuten, mit denen man chatten kann.<\/li>\n<li>Sie brauchen kein aufwendiges Profil zu erstellen.<\/li>\n<\/ul>\n<h3>Nachteile<\/h3>\n<ul>\n<li>Da die Plattform nicht verlangt, dass sich die Nutzer anmelden, bevor sie mit Fremden chatten, kann es vorkommen, dass Sie mit b\u00f6swilligen Nutzern zusammengebracht werden.<\/li>\n<li>Chatruletka wurde wegen der wahnsinnigen Anzahl an nackten Inhalten, die auf der Plattform verf\u00fcgbar sind, als Porno-Plattform bezeichnet<\/li>\n<li>Chatruletka tut sehr wenig, um die Privatsph\u00e4re der Nutzer zu sch\u00fctzen.<\/li>\n<\/ul>\n<h2>Ist Chatruletka sicher in der Anwendung?<\/h2>\n<p>Wenn es um die Sicherheit geht, bef\u00fcrchten wir, dass Chatruletka keine gute Arbeit zum Schutz der Nutzer geleistet hat. Zun\u00e4chst einmal verlangt die Plattform von den Nutzern nicht, dass sie sich f\u00fcr ein Konto anmelden. Das bedeutet, dass jeder der Plattform ohne irgendeine Art von Verifizierung beitreten kann. Das macht Chatruletka zu einer Brutst\u00e4tte f\u00fcr Betr\u00fcger und andere b\u00f6swillige Akteure. Wie bei allen Online-Aktivit\u00e4ten liegt ein Gro\u00dfteil der Verantwortung f\u00fcr Ihre Sicherheit und Privatsph\u00e4re bei Ihnen.<\/p>\n<h2>Schlussfolgerung<\/h2>\n<p>Diese Plattform ist eine gro\u00dfartige Anlaufstelle, wenn Sie nach einer unterhaltsamen Chatseite suchen, auf der Sie mit zuf\u00e4lligen Nutzern aus der ganzen Welt in Kontakt treten k\u00f6nnen. Und da die Plattform kostenlos ist, m\u00fcssen Sie nichts bezahlen, um mit anderen zuf\u00e4lligen Nutzern in Kontakt zu treten, die auf der Suche nach Freunden sind und eine sinnvolle Beziehung aufbauen m\u00f6chten.<\/p>\n<h2>H\u00e4ufig gestellte Fragen \u00fcber Chatruletka<\/h2>\n<h3>Ist Chatruletka kostenlos?<\/h3>\n<p>Eine Sache, die die Leute an der Plattform lieben, ist, dass sie 100% kostenlos ist. Alles, was Sie brauchen, ist Ihr Smartphone oder Ihr Desktop-Computer, um auf die Plattform zuzugreifen.<\/p>\n<h3>Ist Chatruletka eine Dating-Seite?<\/h3>\n<p>Leider ist Chatruletka kein <a href=\"https:\/\/camround.com\/de\/sugar-dating\/\">Partnersuche<\/a> Standort. Es ist eine <a href=\"https:\/\/camround.com\/de\/mnogochat\/\">zuf\u00e4llige Chat-Seite<\/a> genau wie <a href=\"https:\/\/camround.com\/de\/omegle\/\">Omegle<\/a> wo die Nutzer ganz einfach mit zuf\u00e4lligen Nutzern aus der ganzen Welt in Kontakt treten und chatten k\u00f6nnen.<\/p>\n<h3>Ist Chatruletka sicher?<\/h3>\n<p>Obwohl \u00fcber 40 Personen die Chats \u00fcberwachen und moderieren, treffen die Nutzer immer noch auf b\u00f6swillige Nutzer. Wir hoffen, dass Chatruletka mehr tun kann, um die Sicherheit der Nutzer zu gew\u00e4hrleisten.<\/p>\n<h3>Ich mag die Person, mit der ich kommuniziere, nicht - wie kann ich eine neue Beziehung aufbauen?<\/h3>\n<p>Chatruletka hat den Wechsel zwischen Benutzern zu einem Kinderspiel gemacht. Sie brauchen nur auf die Schaltfl\u00e4che \"Weiter\" unter Ihrer Webcam zu dr\u00fccken, und schon sind Sie mit einem anderen zuf\u00e4lligen Benutzer verbunden. Sie k\u00f6nnen so lange auf die Schaltfl\u00e4che \"Weiter\" dr\u00fccken, bis Sie einen Fremden finden, mit dem Sie sich verbinden m\u00f6chten. <a href=\"https:\/\/camround.com\/de\/paltalk\/\">sprechen<\/a> zu.<\/p>\n<h3>Ist es m\u00f6glich, Webcams nicht mehr zu sehen, ohne die Website zu verlassen?<\/h3>\n<p>Nat\u00fcrlich, und der Vorgang ist ziemlich einfach. Klicken Sie einfach auf die Schaltfl\u00e4che \"Stopp\", die sich unter Ihrem Webcam-Bildschirm befindet. Sobald Sie diese Taste dr\u00fccken, wird die Anzeige sofort gestoppt <a href=\"https:\/\/camround.com\/de\/ometv\/\">Webcams<\/a>. Und wenn Sie die Anzeige von Webcams wieder aufnehmen m\u00f6chten, k\u00f6nnen Sie einfach die Schaltfl\u00e4che Start dr\u00fccken.<\/p>\n<h2>Chatruletka - Was bedeutet das eigentlich?<\/h2>\n<p><a href=\"https:\/\/camround.com\/de\/chat42\/\">Zuf\u00e4lliger Video-Chat<\/a> oder Chatruletka, wie es oft genannt wird, ist eine einzigartige <a href=\"https:\/\/camround.com\/de\/chatzy\/\">Chat-App<\/a> die es den Nutzern erm\u00f6glicht, mit zuf\u00e4lligen Fremden auf der ganzen Welt in Kontakt zu treten, entweder \u00fcber ihre Mobiltelefone oder Betriebssysteme.<\/p>\n<p>W\u00e4hrend Chatruletka den Nutzern die M\u00f6glichkeit bietet <a href=\"https:\/\/camround.com\/de\/talk-with-stranger\/\">mit Fremden chatten<\/a> aus einem Land ihrer Wahl, k\u00f6nnen die Nutzer auch mit dem Strom schwimmen, indem sie der Plattform erlauben, sie mit zuf\u00e4lligen Fremden aus zuf\u00e4lligen L\u00e4ndern zu verbinden, die bereit sind, ein Gespr\u00e4ch zu f\u00fchren. Mit Chatruletka erhalten Sie die einmalige Gelegenheit, Ihre bessere H\u00e4lfte kennenzulernen oder eine dauerhafte Freundschaft mit einem zuf\u00e4lligen Fremden aufzubauen, den Sie online kennengelernt haben.<\/p>\n<p>Und wie wir bereits erw\u00e4hnt haben, wird Chatruletka kostenlos angeboten, was es zu einer fantastischen Alternative zu vielen kostenpflichtigen Video-Chat-Apps da drau\u00dfen macht. Mit Chatruletka k\u00f6nnen Sie nicht nur mit zuf\u00e4lligen Fremden in Verbindung treten, oh ja, sondern das auch noch, ohne einen Cent zu bezahlen. Au\u00dferdem erhalten Sie nahtlosen Zugang zu allen ausgezeichneten Funktionen, die auf unserer Plattform verf\u00fcgbar sind.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chatruletka is a popular random video chatting platform. Since the app launched several years ago, it has become the go-to platform for people who want to connect and chat with random strangers across the globe. The platform reportedly has over 200,000 active users. So if you&#8217;re bored and looking for a platform that lets you [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-182","post","type-post","status-publish","format-standard","hentry","category-brands"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chatruletka - Free Video Chat on CamRound.com<\/title>\n<meta name=\"description\" content=\"Live video chat with thousands of strangers like on Chatruletka. Random chat anonymously for free. Chatruletka and many more!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/camround.com\/de\/chatruletka\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chatruletka - Free Video Chat on CamRound.com\" \/>\n<meta property=\"og:description\" content=\"Live video chat with thousands of strangers like on Chatruletka. Random chat anonymously for free. Chatruletka and many more!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/camround.com\/de\/chatruletka\/\" \/>\n<meta property=\"og:site_name\" content=\"CamRound.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T16:43:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T13:26:13+00:00\" \/>\n<meta name=\"author\" content=\"hello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"hello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/\"},\"author\":{\"name\":\"hello\",\"@id\":\"https:\\\/\\\/camround.com\\\/#\\\/schema\\\/person\\\/6a71ec0c934490f98d45c0597b6df0f8\"},\"headline\":\"Chatruletka\",\"datePublished\":\"2024-03-04T16:43:30+00:00\",\"dateModified\":\"2024-03-05T13:26:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/\"},\"wordCount\":1150,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/camround.com\\\/#organization\"},\"articleSection\":[\"Brands\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/camround.com\\\/chatruletka\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/\",\"url\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/\",\"name\":\"Chatruletka - Free Video Chat on CamRound.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camround.com\\\/#website\"},\"datePublished\":\"2024-03-04T16:43:30+00:00\",\"dateModified\":\"2024-03-05T13:26:13+00:00\",\"description\":\"Live video chat with thousands of strangers like on Chatruletka. Random chat anonymously for free. Chatruletka and many more!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/camround.com\\\/chatruletka\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/camround.com\\\/chatruletka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/camround.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chatruletka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/camround.com\\\/#website\",\"url\":\"https:\\\/\\\/camround.com\\\/\",\"name\":\"CamRound\",\"description\":\"Random Video Chat\",\"publisher\":{\"@id\":\"https:\\\/\\\/camround.com\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/camround.com\\\/#organization\",\"name\":\"CamRound\",\"url\":\"https:\\\/\\\/camround.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/camround.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/camround.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/C-Icon_1Color.png\",\"contentUrl\":\"https:\\\/\\\/camround.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/C-Icon_1Color.png\",\"width\":1192,\"height\":1216,\"caption\":\"CamRound\"},\"image\":{\"@id\":\"https:\\\/\\\/camround.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/camround.com\\\/#\\\/schema\\\/person\\\/6a71ec0c934490f98d45c0597b6df0f8\",\"name\":\"hello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g\",\"caption\":\"hello\"},\"sameAs\":[\"https:\\\/\\\/camround.com\"],\"url\":\"https:\\\/\\\/camround.com\\\/de\\\/author\\\/hello\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chatruletka - Kostenloser Video-Chat auf CamRound.com","description":"Live-Video-Chat mit Tausenden von Fremden wie auf Chatruletka. Zufalls-Chat anonym und kostenlos. Chatruletka und viele mehr!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/camround.com\/de\/chatruletka\/","og_locale":"de_DE","og_type":"article","og_title":"Chatruletka - Free Video Chat on CamRound.com","og_description":"Live video chat with thousands of strangers like on Chatruletka. Random chat anonymously for free. Chatruletka and many more!","og_url":"https:\/\/camround.com\/de\/chatruletka\/","og_site_name":"CamRound.com","article_published_time":"2024-03-04T16:43:30+00:00","article_modified_time":"2024-03-05T13:26:13+00:00","author":"hello","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"hello","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/camround.com\/chatruletka\/#article","isPartOf":{"@id":"https:\/\/camround.com\/chatruletka\/"},"author":{"name":"hello","@id":"https:\/\/camround.com\/#\/schema\/person\/6a71ec0c934490f98d45c0597b6df0f8"},"headline":"Chatruletka","datePublished":"2024-03-04T16:43:30+00:00","dateModified":"2024-03-05T13:26:13+00:00","mainEntityOfPage":{"@id":"https:\/\/camround.com\/chatruletka\/"},"wordCount":1150,"commentCount":0,"publisher":{"@id":"https:\/\/camround.com\/#organization"},"articleSection":["Brands"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/camround.com\/chatruletka\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/camround.com\/chatruletka\/","url":"https:\/\/camround.com\/chatruletka\/","name":"Chatruletka - Kostenloser Video-Chat auf CamRound.com","isPartOf":{"@id":"https:\/\/camround.com\/#website"},"datePublished":"2024-03-04T16:43:30+00:00","dateModified":"2024-03-05T13:26:13+00:00","description":"Live-Video-Chat mit Tausenden von Fremden wie auf Chatruletka. Zufalls-Chat anonym und kostenlos. Chatruletka und viele mehr!","breadcrumb":{"@id":"https:\/\/camround.com\/chatruletka\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/camround.com\/chatruletka\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/camround.com\/chatruletka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/camround.com\/"},{"@type":"ListItem","position":2,"name":"Chatruletka"}]},{"@type":"WebSite","@id":"https:\/\/camround.com\/#website","url":"https:\/\/camround.com\/","name":"CamRound","description":"Zuf\u00e4lliger Video-Chat","publisher":{"@id":"https:\/\/camround.com\/#organization"},"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/camround.com\/#organization","name":"CamRound","url":"https:\/\/camround.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/camround.com\/#\/schema\/logo\/image\/","url":"https:\/\/camround.com\/wp-content\/uploads\/2021\/12\/C-Icon_1Color.png","contentUrl":"https:\/\/camround.com\/wp-content\/uploads\/2021\/12\/C-Icon_1Color.png","width":1192,"height":1216,"caption":"CamRound"},"image":{"@id":"https:\/\/camround.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/camround.com\/#\/schema\/person\/6a71ec0c934490f98d45c0597b6df0f8","name":"hallo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ffac2dba7972761e384d31e90361162109b99544c9842bcb6759f39ed2df545?s=96&d=mm&r=g","caption":"hello"},"sameAs":["https:\/\/camround.com"],"url":"https:\/\/camround.com\/de\/author\/hello\/"}]}},"_links":{"self":[{"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/posts\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/comments?post=182"}],"version-history":[{"count":5,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/posts\/182\/revisions"}],"predecessor-version":[{"id":578,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/posts\/182\/revisions\/578"}],"wp:attachment":[{"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/media?parent=182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/categories?post=182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camround.com\/de\/wp-json\/wp\/v2\/tags?post=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}